{"id":3685,"date":"2025-10-21T10:15:18","date_gmt":"2025-10-21T07:15:18","guid":{"rendered":"https:\/\/denta.fi\/?page_id=3685"},"modified":"2025-11-28T12:37:36","modified_gmt":"2025-11-28T10:37:36","slug":"perushammashoito","status":"publish","type":"page","link":"https:\/\/denta.fi\/en\/perushammashoito\/","title":{"rendered":"General dentistry"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3685_ecd215-1c{margin-top:50px;margin-bottom:100px;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:5px;padding-bottom:5px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3685_ecd215-1c{background-image:linear-gradient(90deg,var(--global-palette6) 0%,rgb(225,216,196) 32%,rgb(255,255,255) 32%);}.kb-row-layout-id3685_ecd215-1c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3685_ecd215-1c{background-image:linear-gradient(180deg,var(--global-palette9) 74%,var(--global-palette6) 74%);}}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id3685_ecd215-1c .kb-blocks-bg-video-container,.kb-row-layout-id3685_ecd215-1c .kb-blocks-bg-slider{display:none;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap{padding-top:24px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}@media all and (max-width: 767px){.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap{padding-top:24px;padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id3685_ecd215-1c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3685_ecd215-1c{background-image:linear-gradient(0deg,var(--global-palette6) 35%,var(--global-palette9) 35%);}.kb-row-layout-id3685_ecd215-1c .kb-blocks-bg-video-container,.kb-row-layout-id3685_ecd215-1c .kb-blocks-bg-slider{display:none;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_ecd215-1c alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3685_a10d93-55 > .kt-inside-inner-col{display:flex;}.kadence-column3685_a10d93-55 > .kt-inside-inner-col{min-height:500px;}.kadence-column3685_a10d93-55 > .kt-inside-inner-col,.kadence-column3685_a10d93-55 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_a10d93-55 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_a10d93-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3685_a10d93-55 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3685_a10d93-55{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_a10d93-55{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_a10d93-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3685_a10d93-55 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_a10d93-55{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_a10d93-55 > .kt-inside-inner-col{min-height:300px;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3685_a10d93-55{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_a10d93-55{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_a10d93-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_a10d93-55 > .kt-inside-inner-col{min-height:0px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column3685_a10d93-55{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_a10d93-55{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_a10d93-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_a10d93-55 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.kb-image3685_a6f4f1-c0 .kb-image-has-overlay:after{opacity:0.3;}.kb-image3685_a6f4f1-c0 img.kb-img, .kb-image3685_a6f4f1-c0 .kb-img img{object-position:44% 57.99999999999999%;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3685_a6f4f1-c0 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-land43\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"2400\" src=\"https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22.jpg\" alt=\"moderni ja tyylik\u00e4s hammasl\u00e4\u00e4k\u00e4rin vastaanotto\" class=\"kb-img wp-image-3556\" title=\"\" srcset=\"https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22.jpg 1600w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22-700x1050.jpg 700w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22-200x300.jpg 200w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22-683x1024.jpg 683w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22-768x1152.jpg 768w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22-1024x1536.jpg 1024w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22-1365x2048.jpg 1365w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/09\/180625-Denta-web-22-8x12.jpg 8w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{display:flex;}.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{padding-right:70px;}.kadence-column3685_9b31c7-7b > .kt-inside-inner-col,.kadence-column3685_9b31c7-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3685_9b31c7-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3685_9b31c7-7b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_9b31c7-7b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3685_9b31c7-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_9b31c7-7b{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3685_9b31c7-7b{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_9b31c7-7b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{padding-right:0px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column3685_9b31c7-7b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_9b31c7-7b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3685_9b31c7-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_9b31c7-7b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_5e3e97-92, .wp-block-kadence-advancedheading.kt-adv-heading3685_5e3e97-92[data-kb-block=\"kb-adv-heading3685_5e3e97-92\"]{text-align:left;font-style:normal;text-transform:uppercase;color:#b0a59d;}.wp-block-kadence-advancedheading.kt-adv-heading3685_5e3e97-92 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_5e3e97-92[data-kb-block=\"kb-adv-heading3685_5e3e97-92\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_5e3e97-92 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_5e3e97-92[data-kb-block=\"kb-adv-heading3685_5e3e97-92\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3685_5e3e97-92, .wp-block-kadence-advancedheading.kt-adv-heading3685_5e3e97-92[data-kb-block=\"kb-adv-heading3685_5e3e97-92\"]{font-size:22px;}}<\/style>\n<h1 class=\"kt-adv-heading3685_5e3e97-92 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_5e3e97-92\">Perushammashoito Turussa \u2013 Kaikki hammashoitopalvelut saman katon alla<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Dent \u00c5 tarjoaa kattavat perushammashoidon palvelut Turun keskustassa ammattitaitoisesti ja nykyaikaisella kalustolla. Olitpa sitten s\u00e4\u00e4nn\u00f6llisen hammastarkastuksen, \u00e4killisen hammass\u00e4ryn tai muun hammashoidon tarpeessa, hoidamme sinut nopeasti ja kivuttomasti. Meilt\u00e4 saat kaikki perushammashoidon palvelut ilman l\u00e4hetett\u00e4, ja useimmista hoidoista saat my\u00f6s Kela-korvauksen.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3685_93f9ca-ab{margin-top:0px;}.kb-row-layout-id3685_93f9ca-ab > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_93f9ca-ab > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_93f9ca-ab > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(10% - ((var(--global-kb-gap-none, 0rem ) * 2 )\/3)))minmax(0, calc(15% - ((var(--global-kb-gap-none, 0rem ) * 2 )\/3)))minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 2 )\/3)));}.kb-row-layout-id3685_93f9ca-ab > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3685_93f9ca-ab > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_93f9ca-ab > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3685_93f9ca-ab > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3685_93f9ca-ab > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 1fr) minmax(0, 2fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_93f9ca-ab alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-right-half kt-row-valign-top\">\n<style>.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col,.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col{background-color:#ccbfb6;}.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_d1c0d5-14{position:relative;}.kadence-column3685_d1c0d5-14, .kt-inside-inner-col > .kadence-column3685_d1c0d5-14:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_d1c0d5-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_d1c0d5-14\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3685_9f0505-f2 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-3685_9f0505-f2 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3685_9f0505-f2\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_caf9d5-75 > .kt-inside-inner-col,.kadence-column3685_caf9d5-75 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_caf9d5-75 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_caf9d5-75 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_caf9d5-75 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_caf9d5-75 > .kt-inside-inner-col{background-color:#edebe3;}.kadence-column3685_caf9d5-75 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_caf9d5-75{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_caf9d5-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_caf9d5-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_caf9d5-75\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3685_4c7df6-e1 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-3685_4c7df6-e1 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3685_4c7df6-e1\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_733f9a-a1 > .kt-inside-inner-col{min-height:20px;}.kadence-column3685_733f9a-a1 > .kt-inside-inner-col,.kadence-column3685_733f9a-a1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_733f9a-a1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_733f9a-a1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_733f9a-a1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_733f9a-a1 > .kt-inside-inner-col{background-color:#e1d8c4;}.kadence-column3685_733f9a-a1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_733f9a-a1{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_733f9a-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_733f9a-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_733f9a-a1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3685_ed5f5c-44 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-3685_ed5f5c-44 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3685_ed5f5c-44\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3685_13c8fd-03{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id3685_13c8fd-03 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_13c8fd-03 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_13c8fd-03 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:24px;padding-bottom:24px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3685_13c8fd-03{background-color:#e6e4d8;}.kb-row-layout-id3685_13c8fd-03 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3685_13c8fd-03 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3685_13c8fd-03 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_13c8fd-03 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3685_a68435-dc > .kt-inside-inner-col{padding-top:2%;padding-right:20%;padding-bottom:2%;padding-left:20%;}.kadence-column3685_a68435-dc > .kt-inside-inner-col,.kadence-column3685_a68435-dc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_a68435-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_a68435-dc > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_a68435-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_a68435-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_a68435-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_a68435-dc > .kt-inside-inner-col{padding-right:10%;padding-left:10%;flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_a68435-dc > .kt-inside-inner-col{padding-right:0%;padding-left:0%;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_a68435-dc\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_176727-bb, .wp-block-kadence-advancedheading.kt-adv-heading3685_176727-bb[data-kb-block=\"kb-adv-heading3685_176727-bb\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_176727-bb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_176727-bb[data-kb-block=\"kb-adv-heading3685_176727-bb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_176727-bb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_176727-bb[data-kb-block=\"kb-adv-heading3685_176727-bb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3685_176727-bb wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_176727-bb\">Mit\u00e4 perushammashoito sis\u00e4lt\u00e4\u00e4?<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3685_11a8ac-16, .wp-block-kadence-advancedheading.kt-adv-heading3685_11a8ac-16[data-kb-block=\"kb-adv-heading3685_11a8ac-16\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_11a8ac-16 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_11a8ac-16[data-kb-block=\"kb-adv-heading3685_11a8ac-16\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_11a8ac-16 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_11a8ac-16[data-kb-block=\"kb-adv-heading3685_11a8ac-16\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3685_11a8ac-16 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_11a8ac-16\">Perushammashoito on kaiken suun terveyden perusta. Se kattaa kaikki tavanomaiset hammasl\u00e4\u00e4k\u00e4ripalvelut ennaltaehk\u00e4isev\u00e4st\u00e4 hoidosta korjaaviin toimenpiteisiin. Dent \u00c5:ssa perushammashoitoon kuuluvat s\u00e4\u00e4nn\u00f6lliset hammastarkastukset, paikkaushoidot, juurihoidot, hampaan poistot sek\u00e4 \u00e4killisten vaivojen hoito p\u00e4ivystyksess\u00e4.<br><br>Hammastarkastuksessa selvit\u00e4mme suusi kokonaistilanteen: hampaiston ja ikenien kunnon, limakalvojen terveyden sek\u00e4 purennan toimivuuden. K\u00e4yt\u00e4mme r\u00f6ntgenlaitteita, joilla n\u00e4emme my\u00f6s piilev\u00e4t ongelmat hammasv\u00e4liss\u00e4 ja vanhojen paikkojen alla. Monet hammasvauriot kehittyv\u00e4t hitaasti oireettomina, joten s\u00e4\u00e4nn\u00f6llinen tarkastus on t\u00e4rke\u00e4\u00e4 ongelmien varhaiseksi havaitsemiseksi.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns3685_c78c2c-e4{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns3685_c78c2c-e4 .kt-button{font-weight:normal;font-style:normal;}.kt-btns3685_c78c2c-e4 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3685_c78c2c-e4 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3685_c78c2c-e4 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3685_c78c2c-e4 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3685_c78c2c-e4 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3685_c78c2c-e4 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3685_c78c2c-e4 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3685_c78c2c-e4\"><style>.wp-block-kadence-advancedbtn .kb-btn3685_453ecd-28.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn3685_453ecd-28.kb-button{width:180px;}.wp-block-kadence-advancedbtn .kb-btn3685_453ecd-28.kb-button{color:#e6e4d8;font-size:16px;font-family:'Neue Plak Wide semibold';border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;padding-top:15px;padding-right:10px;padding-bottom:15px;padding-left:10px;}.wp-block-kadence-advancedbtn .kb-btn3685_453ecd-28.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3685_453ecd-28.kb-button:focus{color:var(--global-palette9, #ffffff);background:#343229;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3685_453ecd-28.kb-button{border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3685_453ecd-28.kb-button{border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;}}<\/style><a class=\"kb-button kt-button button kb-btn3685_453ecd-28 kt-btn-size-xlarge kt-btn-width-type-fixed kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/denta.fi\/hinnasto\/\"><span class=\"kt-btn-inner-text\">Hinnasto<\/span><\/a>\n\n<style>.wp-block-kadence-advancedbtn .kb-btn3685_87737b-d2.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn3685_87737b-d2.kb-button{width:180px;}.wp-block-kadence-advancedbtn .kb-btn3685_87737b-d2.kb-button{color:#e6e4d8;font-size:16px;font-family:'Neue Plak Wide semibold';border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;padding-top:15px;padding-right:10px;padding-bottom:15px;padding-left:10px;}.wp-block-kadence-advancedbtn .kb-btn3685_87737b-d2.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3685_87737b-d2.kb-button:focus{color:var(--global-palette9, #ffffff);background:#343229;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3685_87737b-d2.kb-button{border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3685_87737b-d2.kb-button{border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;}}<\/style><a class=\"kb-button kt-button button kb-btn3685_87737b-d2 kt-btn-size-xlarge kt-btn-width-type-fixed kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/denta.fi\/hammaslaakaripaivystys\/\"><span class=\"kt-btn-inner-text\">P\u00e4ivystys<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3685_34b527-67 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_34b527-67 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_34b527-67 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, calc(75% - ((var(--global-kb-gap-none, 0rem ) * 2 )\/3)))minmax(0, calc(15% - ((var(--global-kb-gap-none, 0rem ) * 2 )\/3)))minmax(0, calc(10% - ((var(--global-kb-gap-none, 0rem ) * 2 )\/3)));}.kb-row-layout-id3685_34b527-67 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3685_34b527-67 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_34b527-67 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3685_34b527-67 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3685_34b527-67 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr) minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_34b527-67 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-left-half kt-row-valign-top\">\n<style>.kadence-column3685_acf03e-0c > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column3685_acf03e-0c > .kt-inside-inner-col,.kadence-column3685_acf03e-0c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_acf03e-0c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_acf03e-0c > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_acf03e-0c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_acf03e-0c > .kt-inside-inner-col{background-color:#e1d8c4;}.kadence-column3685_acf03e-0c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_acf03e-0c{position:relative;}.kadence-column3685_acf03e-0c, .kt-inside-inner-col > .kadence-column3685_acf03e-0c:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column3685_acf03e-0c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_acf03e-0c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_acf03e-0c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3685_10bcb9-94 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-3685_10bcb9-94 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3685_10bcb9-94\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_ff8671-c3 > .kt-inside-inner-col,.kadence-column3685_ff8671-c3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_ff8671-c3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_ff8671-c3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_ff8671-c3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_ff8671-c3 > .kt-inside-inner-col{background-color:#edebe3;}.kadence-column3685_ff8671-c3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_ff8671-c3{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_ff8671-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_ff8671-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_ff8671-c3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3685_9b7391-b5 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-3685_9b7391-b5 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3685_9b7391-b5\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_a1aad4-71 > .kt-inside-inner-col{min-height:20px;}.kadence-column3685_a1aad4-71 > .kt-inside-inner-col,.kadence-column3685_a1aad4-71 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_a1aad4-71 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_a1aad4-71 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_a1aad4-71 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_a1aad4-71 > .kt-inside-inner-col{background-color:#ccbfb6;}.kadence-column3685_a1aad4-71 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_a1aad4-71{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_a1aad4-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_a1aad4-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_a1aad4-71\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-3685_e17c0c-30 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-3685_e17c0c-30 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3685_e17c0c-30\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:75px;padding-bottom:75px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3685_9225dd-0c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id3685_9225dd-0c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_9225dd-0c alignnone has-theme-palette7-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3685_ef6ab5-3a > .kt-inside-inner-col,.kadence-column3685_ef6ab5-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_ef6ab5-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_ef6ab5-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_ef6ab5-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_ef6ab5-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_ef6ab5-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_ef6ab5-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_ef6ab5-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_ef6ab5-3a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_514a5a-ea, .wp-block-kadence-advancedheading.kt-adv-heading3685_514a5a-ea[data-kb-block=\"kb-adv-heading3685_514a5a-ea\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_514a5a-ea mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_514a5a-ea[data-kb-block=\"kb-adv-heading3685_514a5a-ea\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_514a5a-ea img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_514a5a-ea[data-kb-block=\"kb-adv-heading3685_514a5a-ea\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading3685_514a5a-ea wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_514a5a-ea\">Kenen tulisi k\u00e4yd\u00e4 hammashoidossa?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Jokainen tarvitsee hammashoitoa l\u00e4pi el\u00e4m\u00e4n. Erityisen t\u00e4rke\u00e4\u00e4 hammashoidossa k\u00e4ynti on silloin, kun suussa on oireita: hammass\u00e4rky\u00e4, ienverenvuotoa, lohkeamia tai muita vaivoja. Hoidamme my\u00f6s hammashoitoa pelk\u00e4\u00e4vi\u00e4 potilaita \u2013 kerro pelostasi, niin huomioimme sen hoidossa.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3685_8b3918-e4, .wp-block-kadence-advancedheading.kt-adv-heading3685_8b3918-e4[data-kb-block=\"kb-adv-heading3685_8b3918-e4\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_8b3918-e4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_8b3918-e4[data-kb-block=\"kb-adv-heading3685_8b3918-e4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_8b3918-e4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_8b3918-e4[data-kb-block=\"kb-adv-heading3685_8b3918-e4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading3685_8b3918-e4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_8b3918-e4\">Miksi valita Dent \u00c5?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Laaja hammasl\u00e4\u00e4k\u00e4ritiimimme koostuu eri alojen osaajista, joten l\u00f6yd\u00e4mme jokaiselle potilaalle sopivan osaajan ja ratkaisun. Saat meilt\u00e4 ajan nopeasti \u2013 usein jopa samana p\u00e4iv\u00e4n\u00e4 akuuteissa tilanteissa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00e4ivystyksemme on Turun kattavin: olemme avoinna my\u00f6s viikonloppuisin, aatoissa ja pyh\u00e4p\u00e4ivin\u00e4 ilman erillisi\u00e4 p\u00e4ivystyslisi\u00e4. T\u00e4m\u00e4 tarkoittaa, ett\u00e4 maksatte vain normaalin toimenpidemaksun, ei kalliita lis\u00e4maksuja. Asiakaspalvelumme voi tehd\u00e4 puhelimessa kiireellisyysarvion ja ohjata oikean hoidon pariin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Taloudelliset huolet eiv\u00e4t ole este hoidolle: tarjoamme jopa 12 kuukauden korotonta maksuaikaa hoidoille (<a href=\"https:\/\/denta.fi\/resurs-bank-info\/\" title=\"\">lue lis\u00e4\u00e4<\/a>). Autamme my\u00f6s Kela-korvausten hakemisessa ja teemme tarvittavat todistukset vakuutusyhti\u00f6it\u00e4 varten. L\u00e4pin\u00e4kyv\u00e4 hinnoittelumme tarkoittaa, ett\u00e4 saat halutessasi aina kustannusarvion ennen hoitoa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sijaitsemme Turun keskustassa erinomaisien kulkuyhteyksien p\u00e4\u00e4ss\u00e4.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns3685_207795-d4{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3685_207795-d4 .kt-button{font-weight:normal;font-style:normal;}.kt-btns3685_207795-d4 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3685_207795-d4 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3685_207795-d4 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3685_207795-d4 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3685_207795-d4 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3685_207795-d4 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3685_207795-d4 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3685_207795-d4\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3685_e3ea14-92.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3685_e3ea14-92.kb-button{color:#e6e4d8;font-size:16px;font-family:'Neue Plak Wide semibold';border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;padding-top:15px;padding-right:10px;padding-bottom:15px;padding-left:10px;}.wp-block-kadence-advancedbtn .kb-btn3685_e3ea14-92.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3685_e3ea14-92.kb-button:focus{color:var(--global-palette9, #ffffff);background:#343229;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3685_e3ea14-92.kb-button{border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3685_e3ea14-92.kb-button{border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;}}<\/style><a class=\"kb-button kt-button button kb-btn3685_e3ea14-92 kt-btn-size-xlarge kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/denta.fi\/henkilokunta\/\"><span class=\"kt-btn-inner-text\">Tutustu henkil\u00f6kuntaamme<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>#wrapper.site{overflow:clip;}.kadence-column3685_c86a47-d3{--kb-section-setting-offset:30px;}.kadence-column3685_c86a47-d3 > .kt-inside-inner-col,.kadence-column3685_c86a47-d3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_c86a47-d3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_c86a47-d3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_c86a47-d3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_c86a47-d3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_c86a47-d3{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_c86a47-d3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_c86a47-d3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_c86a47-d3 kb-section-is-sticky\"><div class=\"kt-inside-inner-col\"><style>.kb-image3685_213053-10 .kb-image-has-overlay:after{opacity:0.3;}.kb-image3685_213053-10 img.kb-img, .kb-image3685_213053-10 .kb-img img{box-shadow:15px 15px 0px 0px var(--global-palette8, #F7FAFC);}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image3685_213053-10:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:50px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3685_213053-10\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-scaled.jpg\" alt=\"\" class=\"kb-img wp-image-3591\" title=\"\" srcset=\"https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-scaled.jpg 2560w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-scaled-700x467.jpg 700w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-300x200.jpg 300w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-1024x683.jpg 1024w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-768x512.jpg 768w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-1536x1024.jpg 1536w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-2048x1365.jpg 2048w, https:\/\/denta.fi\/wp-content\/uploads\/2025\/10\/020925-Denta-print-179-18x12.jpg 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n    <div class=\"denta-reviews-ribbon-container\" aria-labelledby=\"reviews-ribbon-title\">\n        <h2 id=\"reviews-ribbon-title\" class=\"screen-reader-text\">Asiakkaidemme arvostelut<\/h2>\n        \n                <div class=\"denta-reviews-stats\">\n                            <h3 class=\"denta-business-name\">Hammasl\u00e4\u00e4k\u00e4riasema Dent \u00c5<\/h3>\n                        <div class=\"denta-stats-container\">\n                                    <div class=\"denta-stat-item\">\n                        <span class=\"denta-stat-value\">5,0<\/span>\n                        <div class=\"denta-review-stars denta-stat-stars\" style=\"--rating: 5;\"><\/div>\n                    <\/div>\n                                                    <div class=\"denta-stat-item\">\n                        <span class=\"denta-stat-label\">276 arvostelua<\/span>\n                    <\/div>\n                                <div class=\"denta-stat-item\">\n                    <img decoding=\"async\" src=\"https:\/\/denta.fi\/wp-content\/plugins\/denta-google-reviews-ribbon-v3\/images\/google-logo.svg\" alt=\"Google\" class=\"denta-google-logo\" title=\"\">\n                <\/div>\n            <\/div>\n        <\/div>\n                \n        <div class=\"denta-reviews-nav-buttons\">\n            <button class=\"denta-nav-button denta-nav-prev\" aria-label=\"Edellinen arvostelu\">\n                <span class=\"denta-nav-arrow\">\u2039<\/span>\n            <\/button>\n            <button class=\"denta-nav-button denta-nav-next\" aria-label=\"Seuraava arvostelu\">\n                <span class=\"denta-nav-arrow\">\u203a<\/span>\n            <\/button>\n        <\/div>\n        <div class=\"denta-reviews-scroller\" data-review-count=\"4\">\n                            <div class=\"denta-review-card\" data-review-index=\"0\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV84XA_Q610lCaGyRhLViz5Btx98LUfaPL3ZFROSaaXI4ERY6w=s128-c0x00000000-cc-rp-mo\" alt=\"Milla Nieminen\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Milla Nieminen<\/h3>\n                            <div class=\"denta-review-stars\" \n                                 style=\"--rating: 5;\" \n                                 aria-label=\"Arvosana: 5 t\u00e4hte\u00e4 viidest\u00e4\">\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">4 viikkoa sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Super yst\u00e4v\u00e4llisy\u00e4 ja asiantuntevaa palvelua koko klinikalta sek\u00e4 erityisesti hammasl\u00e4\u00e4k\u00e4ri Alankojalta!<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Super yst\u00e4v\u00e4llisy\u00e4 ja asiantuntevaa palvelua koko klinikalta sek\u00e4 erityisesti hammasl\u00e4\u00e4k\u00e4ri Alankojalta!<\/span>\n                                                <\/div>\n                                    <\/div>\n                            <div class=\"denta-review-card\" data-review-index=\"1\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIXyiBLe4fKjN17-QDuBtz9p0vejbJGYGFBDbGi5CEvCaS0tw=s128-c0x00000000-cc-rp-mo-ba3\" alt=\"Hanna Tauriainen\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Hanna Tauriainen<\/h3>\n                            <div class=\"denta-review-stars\" \n                                 style=\"--rating: 5;\" \n                                 aria-label=\"Arvosana: 5 t\u00e4hte\u00e4 viidest\u00e4\">\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">kuukausi sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Tytt\u00e4reni loukkasi perjantaina aamup\u00e4iv\u00e4ll\u00e4 tapaturmaisesti hampaansa. Ihana henkil\u00f6st\u00f6 oli valmis joustamaan ja saimme iltap\u00e4iv\u00e4lle viel\u00e4 ajan. Ajanvarauksessa saimme hyv\u00e4t ohjeet saapumiseen, niin...<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Tytt\u00e4reni loukkasi perjantaina aamup\u00e4iv\u00e4ll\u00e4 tapaturmaisesti hampaansa. Ihana henkil\u00f6st\u00f6 oli valmis joustamaan ja saimme iltap\u00e4iv\u00e4lle viel\u00e4 ajan. Ajanvarauksessa saimme hyv\u00e4t ohjeet saapumiseen, niin ulkopaikkakuntalaisenkin oli helppo l\u00f6yt\u00e4\u00e4 perille. Hammasl\u00e4\u00e4k\u00e4ri Anna-Sofia ja h\u00e4nen avustajansa olivat ihanan empaattisia ja kuuntelivat potilasta. Toimenpiteet selitettiin perusteellisesti, mik\u00e4 loi turvaa ja ennakoivuutta. Saimme selke\u00e4t jatko-ohjeet. Suosittelen!<\/span>\n                                                <\/div>\n                                            <button type=\"button\" class=\"denta-review-source-link denta-read-more-toggle\" aria-expanded=\"false\">\n                            Lue lis\u00e4\u00e4                        <\/button>\n                                    <\/div>\n                            <div class=\"denta-review-card\" data-review-index=\"2\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLaW99UaZXdPX4ivpsm2Fkd4-ZeMVLEJGCgcZOQEPCtKvWoCg=s128-c0x00000000-cc-rp-mo\" alt=\"Mervi Jakonen\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Mervi Jakonen<\/h3>\n                            <div class=\"denta-review-stars\" \n                                 style=\"--rating: 5;\" \n                                 aria-label=\"Arvosana: 5 t\u00e4hte\u00e4 viidest\u00e4\">\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">2 kuukautta sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Ensimm\u00e4inen kerta t\u00e4\u00e4ll\u00e4. Lotta Samooja-T\u00e4hti palautti uskoni hyv\u00e4\u00e4n hammashoitoon.\nEn olisi uskonut ett\u00e4 sanon jopa nauttineeni k\u00e4ynnist\u00e4. Rento ja asiallinen meininki.\n\"nim.pelkuri\"<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Ensimm\u00e4inen kerta t\u00e4\u00e4ll\u00e4. Lotta Samooja-T\u00e4hti palautti uskoni hyv\u00e4\u00e4n hammashoitoon.\nEn olisi uskonut ett\u00e4 sanon jopa nauttineeni k\u00e4ynnist\u00e4. Rento ja asiallinen meininki.\n\"nim.pelkuri\"<\/span>\n                                                <\/div>\n                                    <\/div>\n                            <div class=\"denta-review-card\" data-review-index=\"3\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKlUdZPFx-K75bq-UpRzCMEUHLCxwmCBzIqe1iF86ZGdmEB3w=s128-c0x00000000-cc-rp-mo\" alt=\"Arska Diti\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Arska Diti<\/h3>\n                            <div class=\"denta-review-stars\" \n                                 style=\"--rating: 5;\" \n                                 aria-label=\"Arvosana: 5 t\u00e4hte\u00e4 viidest\u00e4\">\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">5 kuukautta sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Olen eritt\u00e4in tyytyv\u00e4inen saamaani palveluun. L\u00e4\u00e4k\u00e4ri oli perusteellinen, selke\u00e4 ja rehellinen, ja kaikki k\u00e4ytiin huolellisesti l\u00e4pi asiakkaan n\u00e4k\u00f6kulmasta. Arvostin erityisesti sit\u00e4, ett\u00e4 mit\u00e4\u00e4n...<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Olen eritt\u00e4in tyytyv\u00e4inen saamaani palveluun. L\u00e4\u00e4k\u00e4ri oli perusteellinen, selke\u00e4 ja rehellinen, ja kaikki k\u00e4ytiin huolellisesti l\u00e4pi asiakkaan n\u00e4k\u00f6kulmasta. Arvostin erityisesti sit\u00e4, ett\u00e4 mit\u00e4\u00e4n turhaa ei ehdotettu, vaan keskityttiin vain siihen, mik\u00e4 oli oikeasti tarpeellista. Tuomas Tursas teki erinomaista ty\u00f6t\u00e4, ja lopputulos ylitti odotukseni. My\u00f6s kassalla asiointi sujui vaivattomasti, ja maksaminen palvelusetelill\u00e4 sek\u00e4 ePassilla onnistui ongelmitta.<\/span>\n                                                <\/div>\n                                            <button type=\"button\" class=\"denta-review-source-link denta-read-more-toggle\" aria-expanded=\"false\">\n                            Lue lis\u00e4\u00e4                        <\/button>\n                                    <\/div>\n                        \n                                        <div class=\"denta-review-card denta-review-duplicate\" \n                     data-review-index=\"0\" \n                     aria-hidden=\"true\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV84XA_Q610lCaGyRhLViz5Btx98LUfaPL3ZFROSaaXI4ERY6w=s128-c0x00000000-cc-rp-mo\" alt=\"\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Milla Nieminen<\/h3>\n                            <div class=\"denta-review-stars\" style=\"--rating: 5;\"><\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">4 viikkoa sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Super yst\u00e4v\u00e4llisy\u00e4 ja asiantuntevaa palvelua koko klinikalta sek\u00e4 erityisesti hammasl\u00e4\u00e4k\u00e4ri Alankojalta!<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Super yst\u00e4v\u00e4llisy\u00e4 ja asiantuntevaa palvelua koko klinikalta sek\u00e4 erityisesti hammasl\u00e4\u00e4k\u00e4ri Alankojalta!<\/span>\n                                                <\/div>\n                                    <\/div>\n                            <div class=\"denta-review-card denta-review-duplicate\" \n                     data-review-index=\"1\" \n                     aria-hidden=\"true\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIXyiBLe4fKjN17-QDuBtz9p0vejbJGYGFBDbGi5CEvCaS0tw=s128-c0x00000000-cc-rp-mo-ba3\" alt=\"\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Hanna Tauriainen<\/h3>\n                            <div class=\"denta-review-stars\" style=\"--rating: 5;\"><\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">kuukausi sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Tytt\u00e4reni loukkasi perjantaina aamup\u00e4iv\u00e4ll\u00e4 tapaturmaisesti hampaansa. Ihana henkil\u00f6st\u00f6 oli valmis joustamaan ja saimme iltap\u00e4iv\u00e4lle viel\u00e4 ajan. Ajanvarauksessa saimme hyv\u00e4t ohjeet saapumiseen, niin...<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Tytt\u00e4reni loukkasi perjantaina aamup\u00e4iv\u00e4ll\u00e4 tapaturmaisesti hampaansa. Ihana henkil\u00f6st\u00f6 oli valmis joustamaan ja saimme iltap\u00e4iv\u00e4lle viel\u00e4 ajan. Ajanvarauksessa saimme hyv\u00e4t ohjeet saapumiseen, niin ulkopaikkakuntalaisenkin oli helppo l\u00f6yt\u00e4\u00e4 perille. Hammasl\u00e4\u00e4k\u00e4ri Anna-Sofia ja h\u00e4nen avustajansa olivat ihanan empaattisia ja kuuntelivat potilasta. Toimenpiteet selitettiin perusteellisesti, mik\u00e4 loi turvaa ja ennakoivuutta. Saimme selke\u00e4t jatko-ohjeet. Suosittelen!<\/span>\n                                                <\/div>\n                                            <button type=\"button\" class=\"denta-review-source-link denta-read-more-toggle\" aria-expanded=\"false\" tabindex=\"-1\">\n                            Lue lis\u00e4\u00e4                        <\/button>\n                                    <\/div>\n                            <div class=\"denta-review-card denta-review-duplicate\" \n                     data-review-index=\"2\" \n                     aria-hidden=\"true\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLaW99UaZXdPX4ivpsm2Fkd4-ZeMVLEJGCgcZOQEPCtKvWoCg=s128-c0x00000000-cc-rp-mo\" alt=\"\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Mervi Jakonen<\/h3>\n                            <div class=\"denta-review-stars\" style=\"--rating: 5;\"><\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">2 kuukautta sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Ensimm\u00e4inen kerta t\u00e4\u00e4ll\u00e4. Lotta Samooja-T\u00e4hti palautti uskoni hyv\u00e4\u00e4n hammashoitoon.\nEn olisi uskonut ett\u00e4 sanon jopa nauttineeni k\u00e4ynnist\u00e4. Rento ja asiallinen meininki.\n\"nim.pelkuri\"<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Ensimm\u00e4inen kerta t\u00e4\u00e4ll\u00e4. Lotta Samooja-T\u00e4hti palautti uskoni hyv\u00e4\u00e4n hammashoitoon.\nEn olisi uskonut ett\u00e4 sanon jopa nauttineeni k\u00e4ynnist\u00e4. Rento ja asiallinen meininki.\n\"nim.pelkuri\"<\/span>\n                                                <\/div>\n                                    <\/div>\n                            <div class=\"denta-review-card denta-review-duplicate\" \n                     data-review-index=\"3\" \n                     aria-hidden=\"true\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKlUdZPFx-K75bq-UpRzCMEUHLCxwmCBzIqe1iF86ZGdmEB3w=s128-c0x00000000-cc-rp-mo\" alt=\"\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Arska Diti<\/h3>\n                            <div class=\"denta-review-stars\" style=\"--rating: 5;\"><\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">5 kuukautta sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Olen eritt\u00e4in tyytyv\u00e4inen saamaani palveluun. L\u00e4\u00e4k\u00e4ri oli perusteellinen, selke\u00e4 ja rehellinen, ja kaikki k\u00e4ytiin huolellisesti l\u00e4pi asiakkaan n\u00e4k\u00f6kulmasta. Arvostin erityisesti sit\u00e4, ett\u00e4 mit\u00e4\u00e4n...<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Olen eritt\u00e4in tyytyv\u00e4inen saamaani palveluun. L\u00e4\u00e4k\u00e4ri oli perusteellinen, selke\u00e4 ja rehellinen, ja kaikki k\u00e4ytiin huolellisesti l\u00e4pi asiakkaan n\u00e4k\u00f6kulmasta. Arvostin erityisesti sit\u00e4, ett\u00e4 mit\u00e4\u00e4n turhaa ei ehdotettu, vaan keskityttiin vain siihen, mik\u00e4 oli oikeasti tarpeellista. Tuomas Tursas teki erinomaista ty\u00f6t\u00e4, ja lopputulos ylitti odotukseni. My\u00f6s kassalla asiointi sujui vaivattomasti, ja maksaminen palvelusetelill\u00e4 sek\u00e4 ePassilla onnistui ongelmitta.<\/span>\n                                                <\/div>\n                                            <button type=\"button\" class=\"denta-review-source-link denta-read-more-toggle\" aria-expanded=\"false\" tabindex=\"-1\">\n                            Lue lis\u00e4\u00e4                        <\/button>\n                                    <\/div>\n                        \n                                        <div class=\"denta-review-card denta-review-duplicate\" \n                     data-review-index=\"0\" \n                     aria-hidden=\"true\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV84XA_Q610lCaGyRhLViz5Btx98LUfaPL3ZFROSaaXI4ERY6w=s128-c0x00000000-cc-rp-mo\" alt=\"\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Milla Nieminen<\/h3>\n                            <div class=\"denta-review-stars\" style=\"--rating: 5;\"><\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">4 viikkoa sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Super yst\u00e4v\u00e4llisy\u00e4 ja asiantuntevaa palvelua koko klinikalta sek\u00e4 erityisesti hammasl\u00e4\u00e4k\u00e4ri Alankojalta!<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Super yst\u00e4v\u00e4llisy\u00e4 ja asiantuntevaa palvelua koko klinikalta sek\u00e4 erityisesti hammasl\u00e4\u00e4k\u00e4ri Alankojalta!<\/span>\n                                                <\/div>\n                                    <\/div>\n                            <div class=\"denta-review-card denta-review-duplicate\" \n                     data-review-index=\"1\" \n                     aria-hidden=\"true\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIXyiBLe4fKjN17-QDuBtz9p0vejbJGYGFBDbGi5CEvCaS0tw=s128-c0x00000000-cc-rp-mo-ba3\" alt=\"\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Hanna Tauriainen<\/h3>\n                            <div class=\"denta-review-stars\" style=\"--rating: 5;\"><\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">kuukausi sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Tytt\u00e4reni loukkasi perjantaina aamup\u00e4iv\u00e4ll\u00e4 tapaturmaisesti hampaansa. Ihana henkil\u00f6st\u00f6 oli valmis joustamaan ja saimme iltap\u00e4iv\u00e4lle viel\u00e4 ajan. Ajanvarauksessa saimme hyv\u00e4t ohjeet saapumiseen, niin...<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Tytt\u00e4reni loukkasi perjantaina aamup\u00e4iv\u00e4ll\u00e4 tapaturmaisesti hampaansa. Ihana henkil\u00f6st\u00f6 oli valmis joustamaan ja saimme iltap\u00e4iv\u00e4lle viel\u00e4 ajan. Ajanvarauksessa saimme hyv\u00e4t ohjeet saapumiseen, niin ulkopaikkakuntalaisenkin oli helppo l\u00f6yt\u00e4\u00e4 perille. Hammasl\u00e4\u00e4k\u00e4ri Anna-Sofia ja h\u00e4nen avustajansa olivat ihanan empaattisia ja kuuntelivat potilasta. Toimenpiteet selitettiin perusteellisesti, mik\u00e4 loi turvaa ja ennakoivuutta. Saimme selke\u00e4t jatko-ohjeet. Suosittelen!<\/span>\n                                                <\/div>\n                                            <button type=\"button\" class=\"denta-review-source-link denta-read-more-toggle\" aria-expanded=\"false\" tabindex=\"-1\">\n                            Lue lis\u00e4\u00e4                        <\/button>\n                                    <\/div>\n                            <div class=\"denta-review-card denta-review-duplicate\" \n                     data-review-index=\"2\" \n                     aria-hidden=\"true\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLaW99UaZXdPX4ivpsm2Fkd4-ZeMVLEJGCgcZOQEPCtKvWoCg=s128-c0x00000000-cc-rp-mo\" alt=\"\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Mervi Jakonen<\/h3>\n                            <div class=\"denta-review-stars\" style=\"--rating: 5;\"><\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">2 kuukautta sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Ensimm\u00e4inen kerta t\u00e4\u00e4ll\u00e4. Lotta Samooja-T\u00e4hti palautti uskoni hyv\u00e4\u00e4n hammashoitoon.\nEn olisi uskonut ett\u00e4 sanon jopa nauttineeni k\u00e4ynnist\u00e4. Rento ja asiallinen meininki.\n\"nim.pelkuri\"<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Ensimm\u00e4inen kerta t\u00e4\u00e4ll\u00e4. Lotta Samooja-T\u00e4hti palautti uskoni hyv\u00e4\u00e4n hammashoitoon.\nEn olisi uskonut ett\u00e4 sanon jopa nauttineeni k\u00e4ynnist\u00e4. Rento ja asiallinen meininki.\n\"nim.pelkuri\"<\/span>\n                                                <\/div>\n                                    <\/div>\n                            <div class=\"denta-review-card denta-review-duplicate\" \n                     data-review-index=\"3\" \n                     aria-hidden=\"true\">\n                    <div class=\"denta-review-card-header\">\n                                                    <img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKlUdZPFx-K75bq-UpRzCMEUHLCxwmCBzIqe1iF86ZGdmEB3w=s128-c0x00000000-cc-rp-mo\" alt=\"\" class=\"denta-review-author-avatar\" loading=\"lazy\" width=\"40\" height=\"40\" title=\"\">\n                                                <div class=\"denta-review-author-info\">\n                            <h3 class=\"denta-review-author-name\">Arska Diti<\/h3>\n                            <div class=\"denta-review-stars\" style=\"--rating: 5;\"><\/div>\n                        <\/div>\n                    <\/div>\n                                            <p class=\"denta-review-time\">5 kuukautta sitten<\/p>\n                                        <div class=\"denta-review-text\">\n                                                    <span class=\"denta-review-text-short\">Olen eritt\u00e4in tyytyv\u00e4inen saamaani palveluun. L\u00e4\u00e4k\u00e4ri oli perusteellinen, selke\u00e4 ja rehellinen, ja kaikki k\u00e4ytiin huolellisesti l\u00e4pi asiakkaan n\u00e4k\u00f6kulmasta. Arvostin erityisesti sit\u00e4, ett\u00e4 mit\u00e4\u00e4n...<\/span>\n                            <span class=\"denta-review-text-full\" hidden>Olen eritt\u00e4in tyytyv\u00e4inen saamaani palveluun. L\u00e4\u00e4k\u00e4ri oli perusteellinen, selke\u00e4 ja rehellinen, ja kaikki k\u00e4ytiin huolellisesti l\u00e4pi asiakkaan n\u00e4k\u00f6kulmasta. Arvostin erityisesti sit\u00e4, ett\u00e4 mit\u00e4\u00e4n turhaa ei ehdotettu, vaan keskityttiin vain siihen, mik\u00e4 oli oikeasti tarpeellista. Tuomas Tursas teki erinomaista ty\u00f6t\u00e4, ja lopputulos ylitti odotukseni. My\u00f6s kassalla asiointi sujui vaivattomasti, ja maksaminen palvelusetelill\u00e4 sek\u00e4 ePassilla onnistui ongelmitta.<\/span>\n                                                <\/div>\n                                            <button type=\"button\" class=\"denta-review-source-link denta-read-more-toggle\" aria-expanded=\"false\" tabindex=\"-1\">\n                            Lue lis\u00e4\u00e4                        <\/button>\n                                    <\/div>\n                    <\/div>\n        <div class=\"denta-reviews-actions\">\n                            <a href=\"https:\/\/search.google.com\/local\/writereview?placeid=ChIJNSNGz_B3jEYR5GWHuvQvLdU\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"denta-write-review-button\">\n                    J\u00e4t\u00e4 arvostelu                <\/a>\n                <a href=\"https:\/\/www.google.com\/maps\/search\/?api=1&amp;query=Google&amp;query_place_id=ChIJNSNGz_B3jEYR5GWHuvQvLdU\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"denta-watch-all-reviews-button denta-write-review-button\">\n                    Kaikki arvostelut                <\/a>\n                    <\/div>\n    <\/div>\n    \n\n\n<style>.kb-row-layout-id3685_9dbaf7-73 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_9dbaf7-73 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_9dbaf7-73 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:75px;padding-right:70px;padding-bottom:75px;padding-left:70px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3685_9dbaf7-73 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3685_9dbaf7-73 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3685_9dbaf7-73 > .kt-row-column-wrap{padding-right:20px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_9dbaf7-73 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3685_d0c347-d6 > .kt-inside-inner-col,.kadence-column3685_d0c347-d6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_d0c347-d6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_d0c347-d6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_d0c347-d6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_d0c347-d6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_d0c347-d6{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_d0c347-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_d0c347-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_d0c347-d6\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_87d830-70, .wp-block-kadence-advancedheading.kt-adv-heading3685_87d830-70[data-kb-block=\"kb-adv-heading3685_87d830-70\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_87d830-70 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_87d830-70[data-kb-block=\"kb-adv-heading3685_87d830-70\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_87d830-70 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_87d830-70[data-kb-block=\"kb-adv-heading3685_87d830-70\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3685_87d830-70 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_87d830-70\">Perushammashoidon palvelumme<\/h2>\n\n\n<style>.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-lg, 4rem);padding-top:50px;padding-bottom:24px;}.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3685_c49277-b7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3685_c49277-b7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_c49277-b7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-two-grid kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3685_0eebb9-d3 > .kt-inside-inner-col,.kadence-column3685_0eebb9-d3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_0eebb9-d3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_0eebb9-d3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_0eebb9-d3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_0eebb9-d3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_0eebb9-d3{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_0eebb9-d3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_0eebb9-d3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_0eebb9-d3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55, .wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55[data-kb-block=\"kb-adv-heading3685_3316fd-55\"]{padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-left:0px;font-style:normal;border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55[data-kb-block=\"kb-adv-heading3685_3316fd-55\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55[data-kb-block=\"kb-adv-heading3685_3316fd-55\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55, .wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55[data-kb-block=\"kb-adv-heading3685_3316fd-55\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55, .wp-block-kadence-advancedheading.kt-adv-heading3685_3316fd-55[data-kb-block=\"kb-adv-heading3685_3316fd-55\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}<\/style>\n<h3 class=\"kt-adv-heading3685_3316fd-55 wp-block-kadence-advancedheading has-theme-palette-7-background-color has-background\" data-kb-block=\"kb-adv-heading3685_3316fd-55\">Hammastarkastus \u2013 suun terveyden perusta<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3685_ebfb58-6d, .wp-block-kadence-advancedheading.kt-adv-heading3685_ebfb58-6d[data-kb-block=\"kb-adv-heading3685_ebfb58-6d\"]{padding-left:10px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_ebfb58-6d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_ebfb58-6d[data-kb-block=\"kb-adv-heading3685_ebfb58-6d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_ebfb58-6d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_ebfb58-6d[data-kb-block=\"kb-adv-heading3685_ebfb58-6d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3685_ebfb58-6d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_ebfb58-6d\">S\u00e4\u00e4nn\u00f6llinen tarkastus 1-2 vuoden v\u00e4lein paljastaa piilev\u00e4t ongelmat ajoissa. Tarkastukseen sis\u00e4ltyy hampaiden, ikenien ja limakalvojen tutkimus, purennan arviointi sek\u00e4 tarvittaessa r\u00f6ntgenkuvat. Saat henkil\u00f6kohtaisen hoitosuunnitelman ja ohjausta kotihoitoon. Kela korvaa tarkastuksen joka toinen vuosi ellei hammasl\u00e4\u00e4k\u00e4ri ole todennut l\u00e4\u00e4ketieteellist\u00e4 tarvetta vuosittaiseen tarkastukseen.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_272620-4c > .kt-inside-inner-col,.kadence-column3685_272620-4c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_272620-4c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_272620-4c > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_272620-4c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_272620-4c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_272620-4c{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_272620-4c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_272620-4c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_272620-4c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd, .wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd[data-kb-block=\"kb-adv-heading3685_e572ed-fd\"]{padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-left:0px;font-style:normal;border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd[data-kb-block=\"kb-adv-heading3685_e572ed-fd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd[data-kb-block=\"kb-adv-heading3685_e572ed-fd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd, .wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd[data-kb-block=\"kb-adv-heading3685_e572ed-fd\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd, .wp-block-kadence-advancedheading.kt-adv-heading3685_e572ed-fd[data-kb-block=\"kb-adv-heading3685_e572ed-fd\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}<\/style>\n<h3 class=\"kt-adv-heading3685_e572ed-fd wp-block-kadence-advancedheading has-theme-palette-7-background-color has-background\" data-kb-block=\"kb-adv-heading3685_e572ed-fd\">P\u00e4ivystys \u2013 apua akuuttiin hammass\u00e4rkyyn<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3685_647048-cd, .wp-block-kadence-advancedheading.kt-adv-heading3685_647048-cd[data-kb-block=\"kb-adv-heading3685_647048-cd\"]{padding-left:10px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_647048-cd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_647048-cd[data-kb-block=\"kb-adv-heading3685_647048-cd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_647048-cd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_647048-cd[data-kb-block=\"kb-adv-heading3685_647048-cd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3685_647048-cd wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_647048-cd\">\u00c4killinen hammass\u00e4rky tai tapaturma vaatii nopeaa hoitoa. P\u00e4ivystyksess\u00e4mme hoidamme kiireelliset vaivat: tulehdukset, lohkeamat, traumat ja kovimmatkin s\u00e4ryt. Jos hammass\u00e4rkyyn liittyy turvotusta tai hammas on irronnut tapaturmassa, hakeudu v\u00e4litt\u00f6m\u00e4sti hoitoon. P\u00e4ivyst\u00e4mme my\u00f6s viikonloppuisin ilman lis\u00e4maksuja.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_2de60e-1d > .kt-inside-inner-col,.kadence-column3685_2de60e-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_2de60e-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_2de60e-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_2de60e-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_2de60e-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_2de60e-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_2de60e-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_2de60e-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_2de60e-1d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97, .wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97[data-kb-block=\"kb-adv-heading3685_783a5e-97\"]{padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-left:0px;font-style:normal;border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97[data-kb-block=\"kb-adv-heading3685_783a5e-97\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97[data-kb-block=\"kb-adv-heading3685_783a5e-97\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97, .wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97[data-kb-block=\"kb-adv-heading3685_783a5e-97\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97, .wp-block-kadence-advancedheading.kt-adv-heading3685_783a5e-97[data-kb-block=\"kb-adv-heading3685_783a5e-97\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}<\/style>\n<h3 class=\"kt-adv-heading3685_783a5e-97 wp-block-kadence-advancedheading has-theme-palette-7-background-color has-background\" data-kb-block=\"kb-adv-heading3685_783a5e-97\">Paikkaushoito \u2013 rei\u00e4t ja lohkeamat kuntoon<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3685_ced28f-ba, .wp-block-kadence-advancedheading.kt-adv-heading3685_ced28f-ba[data-kb-block=\"kb-adv-heading3685_ced28f-ba\"]{padding-left:10px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_ced28f-ba mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_ced28f-ba[data-kb-block=\"kb-adv-heading3685_ced28f-ba\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_ced28f-ba img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_ced28f-ba[data-kb-block=\"kb-adv-heading3685_ced28f-ba\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3685_ced28f-ba wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_ced28f-ba\">Korjaamme hammasvauriot yhdistelm\u00e4muovilla tai keraamisilla t\u00e4ytteill\u00e4. Paikkaushoito tehd\u00e4\u00e4n yleisimmin puudutuksessa kivuttomasti. Mit\u00e4 aikaisemmin reik\u00e4 paikataan, sit\u00e4 pienempi toimenpide riitt\u00e4\u00e4.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_4e1974-6a > .kt-inside-inner-col,.kadence-column3685_4e1974-6a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_4e1974-6a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_4e1974-6a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_4e1974-6a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_4e1974-6a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_4e1974-6a{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_4e1974-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_4e1974-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_4e1974-6a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43, .wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43[data-kb-block=\"kb-adv-heading3685_1f6de4-43\"]{padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-left:0px;font-style:normal;border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43[data-kb-block=\"kb-adv-heading3685_1f6de4-43\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43[data-kb-block=\"kb-adv-heading3685_1f6de4-43\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43, .wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43[data-kb-block=\"kb-adv-heading3685_1f6de4-43\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43, .wp-block-kadence-advancedheading.kt-adv-heading3685_1f6de4-43[data-kb-block=\"kb-adv-heading3685_1f6de4-43\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}<\/style>\n<h3 class=\"kt-adv-heading3685_1f6de4-43 wp-block-kadence-advancedheading has-theme-palette-7-background-color has-background\" data-kb-block=\"kb-adv-heading3685_1f6de4-43\">Juurihoito \u2013 hampaan pelastus<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3685_104a56-3b, .wp-block-kadence-advancedheading.kt-adv-heading3685_104a56-3b[data-kb-block=\"kb-adv-heading3685_104a56-3b\"]{padding-left:10px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_104a56-3b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_104a56-3b[data-kb-block=\"kb-adv-heading3685_104a56-3b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_104a56-3b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_104a56-3b[data-kb-block=\"kb-adv-heading3685_104a56-3b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3685_104a56-3b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_104a56-3b\">Juurihoitoon voivat johtaa esimerkiksi trauma tai syv\u00e4lle edennyt reik\u00e4 mik\u00e4 on vaurioittanut hampaan ytimen. <br>Juurihoidossa hampaan ydinontelo puhdistetaan ja desinfioidaan, sek\u00e4 lopuksi juurikanavat t\u00e4ytet\u00e4\u00e4n juurent\u00e4ytteell\u00e4. Juurihoito tehd\u00e4\u00e4n paikallispuudutuksessa.<br>Juurihoidettu hammas on aina heikompi kuin koskematon hammas. T\u00e4m\u00e4n vuoksi usein suosittelemme juurihoidettuun hampaaseen keraamista paikkaa tai kruunua est\u00e4m\u00e4\u00e4n hammasta lohkeamiselta tai halkeamiselta.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-lg, 4rem);padding-top:50px;padding-bottom:24px;}.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3685_0b939f-3f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3685_0b939f-3f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_0b939f-3f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-two-grid kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3685_cbca52-dd > .kt-inside-inner-col,.kadence-column3685_cbca52-dd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_cbca52-dd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_cbca52-dd > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_cbca52-dd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_cbca52-dd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_cbca52-dd{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_cbca52-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_cbca52-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_cbca52-dd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8, .wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8[data-kb-block=\"kb-adv-heading3685_86cbed-f8\"]{padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-left:0px;font-style:normal;border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8[data-kb-block=\"kb-adv-heading3685_86cbed-f8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8[data-kb-block=\"kb-adv-heading3685_86cbed-f8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8, .wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8[data-kb-block=\"kb-adv-heading3685_86cbed-f8\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8, .wp-block-kadence-advancedheading.kt-adv-heading3685_86cbed-f8[data-kb-block=\"kb-adv-heading3685_86cbed-f8\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}<\/style>\n<h3 class=\"kt-adv-heading3685_86cbed-f8 wp-block-kadence-advancedheading has-theme-palette-7-background-color has-background\" data-kb-block=\"kb-adv-heading3685_86cbed-f8\">Hampaan poisto<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3685_bf72f2-93, .wp-block-kadence-advancedheading.kt-adv-heading3685_bf72f2-93[data-kb-block=\"kb-adv-heading3685_bf72f2-93\"]{padding-left:10px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_bf72f2-93 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_bf72f2-93[data-kb-block=\"kb-adv-heading3685_bf72f2-93\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_bf72f2-93 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_bf72f2-93[data-kb-block=\"kb-adv-heading3685_bf72f2-93\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3685_bf72f2-93 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_bf72f2-93\">Joskus hammas on niin pahasti vaurioitunut, ettei sit\u00e4 voida en\u00e4\u00e4 korjata. Huolellisella puudutuksella varmistetaan, ett\u00e4 hampaan poisto on t\u00e4ysin kivuton toimenpide. Yleisimpi\u00e4 poiston syit\u00e4 ovat laajat lohkeamat, syv\u00e4t rei\u00e4t, viisaudenhampaat tai oikomishoidon vaatimat poistot. Annamme selke\u00e4t j\u00e4lkihoito-ohjeet paranemisen varmistamiseksi.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_fa5001-3b > .kt-inside-inner-col,.kadence-column3685_fa5001-3b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_fa5001-3b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_fa5001-3b > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_fa5001-3b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_fa5001-3b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_fa5001-3b{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_fa5001-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_fa5001-3b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_fa5001-3b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3, .wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3[data-kb-block=\"kb-adv-heading3685_7b13a8-d3\"]{padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-left:0px;font-style:normal;border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}.wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3[data-kb-block=\"kb-adv-heading3685_7b13a8-d3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3[data-kb-block=\"kb-adv-heading3685_7b13a8-d3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3, .wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3[data-kb-block=\"kb-adv-heading3685_7b13a8-d3\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3, .wp-block-kadence-advancedheading.kt-adv-heading3685_7b13a8-d3[data-kb-block=\"kb-adv-heading3685_7b13a8-d3\"]{border-top:1px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette1, #3182CE);}}<\/style>\n<h3 class=\"kt-adv-heading3685_7b13a8-d3 wp-block-kadence-advancedheading has-theme-palette-7-background-color has-background\" data-kb-block=\"kb-adv-heading3685_7b13a8-d3\">Hoito pelkopotilaille<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3685_4afcd3-87, .wp-block-kadence-advancedheading.kt-adv-heading3685_4afcd3-87[data-kb-block=\"kb-adv-heading3685_4afcd3-87\"]{padding-left:10px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_4afcd3-87 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_4afcd3-87[data-kb-block=\"kb-adv-heading3685_4afcd3-87\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_4afcd3-87 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_4afcd3-87[data-kb-block=\"kb-adv-heading3685_4afcd3-87\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3685_4afcd3-87 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_4afcd3-87\">Ymm\u00e4rr\u00e4mme, ett\u00e4 hammashoito voi j\u00e4nnitt\u00e4\u00e4. Keskustelemme peloistasi ja r\u00e4\u00e4t\u00e4l\u00f6imme hoidon yksil\u00f6llisesti. Voimme k\u00e4ytt\u00e4\u00e4 rentouttavaa esil\u00e4\u00e4kityst\u00e4 tai tehd\u00e4 laajemmat hoidot nukutuksessa. Rauhallinen ilmapiirimme ja kokenut henkil\u00f6kuntamme tekev\u00e4t k\u00e4ynnist\u00e4 mahdollisimman miellytt\u00e4v\u00e4n.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3685_cf8e4a-c6 > .kt-inside-inner-col,.kadence-column3685_cf8e4a-c6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_cf8e4a-c6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_cf8e4a-c6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_cf8e4a-c6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_cf8e4a-c6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_cf8e4a-c6{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_cf8e4a-c6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_cf8e4a-c6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_cf8e4a-c6\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3685_932f5c-12 > .kt-inside-inner-col,.kadence-column3685_932f5c-12 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_932f5c-12 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_932f5c-12 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_932f5c-12 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_932f5c-12 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_932f5c-12{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_932f5c-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_932f5c-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_932f5c-12\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedbtn.kb-btns3685_06a146-5b{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns3685_06a146-5b .kt-button{font-weight:normal;font-style:normal;}.kt-btns3685_06a146-5b .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3685_06a146-5b .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3685_06a146-5b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3685_06a146-5b .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3685_06a146-5b .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3685_06a146-5b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3685_06a146-5b .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3685_06a146-5b\"><style>.wp-block-kadence-advancedbtn .kb-btn3685_8b7a9d-a8.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn3685_8b7a9d-a8.kb-button{width:180px;}.wp-block-kadence-advancedbtn .kb-btn3685_8b7a9d-a8.kb-button{color:#e6e4d8;font-size:16px;font-family:'Neue Plak Wide semibold';border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;padding-top:15px;padding-right:10px;padding-bottom:15px;padding-left:10px;}.wp-block-kadence-advancedbtn .kb-btn3685_8b7a9d-a8.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3685_8b7a9d-a8.kb-button:focus{color:var(--global-palette9, #ffffff);background:#343229;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3685_8b7a9d-a8.kb-button{border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3685_8b7a9d-a8.kb-button{border-top:2px solid #ccbfb6;border-right:2px solid #ccbfb6;border-bottom:2px solid #ccbfb6;border-left:2px solid #ccbfb6;}}<\/style><a class=\"kb-button kt-button button kb-btn3685_8b7a9d-a8 kt-btn-size-xlarge kt-btn-width-type-fixed kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/denta.fi\/hinnasto\/\"><span class=\"kt-btn-inner-text\">Hinnasto<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3685_ad1141-8b{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id3685_ad1141-8b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3685_ad1141-8b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3685_ad1141-8b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:24px;padding-bottom:75px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3685_ad1141-8b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3685_ad1141-8b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3685_ad1141-8b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3685_ad1141-8b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3685_0c0bff-43 > .kt-inside-inner-col{padding-top:2%;padding-right:20%;padding-bottom:2%;padding-left:20%;}.kadence-column3685_0c0bff-43 > .kt-inside-inner-col,.kadence-column3685_0c0bff-43 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3685_0c0bff-43 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3685_0c0bff-43 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3685_0c0bff-43 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3685_0c0bff-43 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3685_0c0bff-43{position:relative;}@media all and (max-width: 1024px){.kadence-column3685_0c0bff-43 > .kt-inside-inner-col{padding-right:10%;padding-left:10%;flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3685_0c0bff-43 > .kt-inside-inner-col{padding-right:2%;padding-left:2%;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3685_0c0bff-43\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3685_7bb9bc-09, .wp-block-kadence-advancedheading.kt-adv-heading3685_7bb9bc-09[data-kb-block=\"kb-adv-heading3685_7bb9bc-09\"]{padding-bottom:30px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3685_7bb9bc-09 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3685_7bb9bc-09[data-kb-block=\"kb-adv-heading3685_7bb9bc-09\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3685_7bb9bc-09 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3685_7bb9bc-09[data-kb-block=\"kb-adv-heading3685_7bb9bc-09\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3685_7bb9bc-09 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3685_7bb9bc-09\">Usein kysytyt kysymykset<\/h2>\n\n\n<style>.kt-accordion-id3685_ca6923-3f .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:15px;}.kt-accordion-id3685_ca6923-3f .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #353536;border-right-color:#e1d8c4;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#e1d8c4;border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f6f5f1;font-size:20px;font-family:'Neue Plak Wide semibold';color:#555555;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#e1d8c4;}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#e1d8c4;}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f6f5f1;}.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3685_ca6923-3f .kt-blocks-accordion-header:focus-visible{color:#555555;background:#e9e4d6;border-top:1px solid #353536;border-right-color:#eeeeee;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette9, #ffffff);}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#e9e4d6;}.kt-accordion-id3685_ca6923-3f .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#555555;background:#e9e4d6;border-top:1px solid #353536;border-right-color:#444444;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette9, #ffffff);}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette9, #ffffff);}.kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3685_ca6923-3f:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#e9e4d6;}@media all and (max-width: 1024px){.kt-accordion-id3685_ca6923-3f .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #353536;border-right-color:#e1d8c4;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#e1d8c4;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3685_ca6923-3f .kt-blocks-accordion-header:focus-visible{border-top:1px solid #353536;border-right-color:#eeeeee;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id3685_ca6923-3f .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #353536;border-right-color:#444444;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id3685_ca6923-3f .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3685_ca6923-3f .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:15px;}.kt-accordion-id3685_ca6923-3f .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #353536;border-right-color:#e1d8c4;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#e1d8c4;border-left-style:solid;font-size:16px;}.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3685_ca6923-3f .kt-blocks-accordion-header:focus-visible{border-top:1px solid #353536;border-right-color:#eeeeee;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id3685_ca6923-3f .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3685_ca6923-3f > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #353536;border-right-color:#444444;border-right-style:solid;border-bottom:3px solid #e1d8c4;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3685_ca6923-3f kt-accordion-has-9-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basiccircle kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"true\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane3685_e5d243-16\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Kuinka usein hammastarkastuksessa pit\u00e4\u00e4 k\u00e4yd\u00e4?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"wp-block-paragraph\">Aikuisille riitt\u00e4\u00e4 yleens\u00e4 tarkastus 1-2 vuoden v\u00e4lein, mutta yksil\u00f6lliset tarpeet vaihtelevat. Jos sinulla on taipumusta reikiintymiseen, ientulehdukseen tai muihin ongelmiin, suosittelemme tihe\u00e4mpi\u00e4 k\u00e4yntej\u00e4. Lapsille ja nuorille suositellaan vuosittaista tarkastusta.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane3685_37d669-ac\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Mit\u00e4 teen \u00e4killiseen hammass\u00e4rkyyn?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"wp-block-paragraph\">Ota s\u00e4rkyl\u00e4\u00e4kett\u00e4 (ibuprofeeni tai parasetamoli) ja varaa aika p\u00e4ivystykseen. Jos s\u00e4rkyyn liittyy turvotusta, kuumetta tai nielemis- ja hengitysvaikeuksia, hakeudu hoitoon v\u00e4litt\u00f6m\u00e4sti. Kylm\u00e4pakkaus poskelle voi helpottaa turvotusta.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane3685_9801e6-66\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Saanko Kela-korvausta perushammashoidosta?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"wp-block-paragraph\">Kyll\u00e4, saat Kela-korvauksen hammastarkastuksesta, paikkaushoidosta, juurihoidosta ja hampaan poistosta. Korvaus on noin 15-40% hoidon hinnasta riippuen toimenpiteest\u00e4. <\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-8 kt-pane3685_888cf9-29\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Voiko hammashoitoa saada nukutuksessa?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"wp-block-paragraph\">Kyll\u00e4, tarjoamme mahdollisuuden hoitaa hampaat nukutuksessa erityisesti pelkopotilaille tai laajoissa toimenpiteiss\u00e4. Nukutushoito soveltuu hyvin esimerkiksi usean hampaan hoitoon kerralla. Keskustele hammasl\u00e4\u00e4k\u00e4rin kanssa nukutusvaihtoehdoista.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-9 kt-pane3685_8a393c-66\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Miten voin est\u00e4\u00e4 hammasongelmia?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p class=\"wp-block-paragraph\">Hyv\u00e4 kotihoito on paras ennaltaehk\u00e4isy: harjaa hampaat kahdesti p\u00e4iv\u00e4ss\u00e4 fluorihammastahnalla ja puhdista hammasv\u00e4lit p\u00e4ivitt\u00e4in. V\u00e4lt\u00e4 jatkuvaa napostelua ja sokeripitoisia juomia. K\u00e4y s\u00e4\u00e4nn\u00f6llisesti hammastarkastuksessa ja suuhygienistill\u00e4.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Perushammashoito Turussa \u2013 Kaikki hammashoitopalvelut saman katon alla Dent \u00c5 tarjoaa kattavat perushammashoidon palvelut Turun keskustassa ammattitaitoisesti ja nykyaikaisella kalustolla. Olitpa sitten s\u00e4\u00e4nn\u00f6llisen hammastarkastuksen, \u00e4killisen hammass\u00e4ryn tai muun hammashoidon tarpeessa, hoidamme sinut nopeasti ja kivuttomasti. Meilt\u00e4 saat kaikki perushammashoidon palvelut ilman l\u00e4hetett\u00e4, ja useimmista hoidoista saat my\u00f6s Kela-korvauksen. Mit\u00e4 perushammashoito sis\u00e4lt\u00e4\u00e4? Perushammashoito on kaiken suun&#8230;<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3685","page","type-page","status-publish","hentry"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Peter Puhakka","author_link":"https:\/\/denta.fi\/en\/author\/peter_piinkova\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/denta.fi\/en\/wp-json\/wp\/v2\/pages\/3685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denta.fi\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/denta.fi\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/denta.fi\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/denta.fi\/en\/wp-json\/wp\/v2\/comments?post=3685"}],"version-history":[{"count":20,"href":"https:\/\/denta.fi\/en\/wp-json\/wp\/v2\/pages\/3685\/revisions"}],"predecessor-version":[{"id":3896,"href":"https:\/\/denta.fi\/en\/wp-json\/wp\/v2\/pages\/3685\/revisions\/3896"}],"wp:attachment":[{"href":"https:\/\/denta.fi\/en\/wp-json\/wp\/v2\/media?parent=3685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}